{"id":17404,"date":"2018-02-27T11:47:16","date_gmt":"2018-02-27T10:47:16","guid":{"rendered":"https:\/\/estanteriasrecord.com\/blog\/la-technologie-est-de-plus-en-plus-presente-dans-la-logistique"},"modified":"2025-02-24T18:03:21","modified_gmt":"2025-02-24T17:03:21","slug":"revolution-technologique-secteur-logistique-et-stockage","status":"publish","type":"post","link":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/","title":{"rendered":"La technologie est de plus en plus pr\u00e9sente dans la logistique."},"content":{"rendered":"<p><span style=\"font-size: 11pt;\">La <strong>r\u00e9volution technologique<\/strong> que nous vivons a <strong>un impact de plus en plus fort <\/strong>dans le monde de la l<strong>ogistique et du stockage<\/strong>. De plus en plus d&rsquo;entreprises vendent un plus grand nombre de produits en ligne et ont besoin de services de livraison plus rapides et meilleurs, que le client appr\u00e9cie, et qui influent sur son niveau de satisfaction du vendeur. <\/span><\/p>\n<p><span style=\"font-size: 11pt;\">De plus, de nombreux <strong>processus de stockage sont devenus obsol\u00e8tes<\/strong> laissant les entreprises traditionnellement h\u00e9g\u00e9moniques dans des situations d\u00e9licates et \u00e0 l&rsquo;avenir incertain.<\/span><\/p>\n<p><span style=\"font-size: 11pt;\">Dans ce nouvel environnement apparaissent de nouveaux mod\u00e8les logistiques et d&rsquo;entreposage tels que le <strong>cross docking<\/strong> o\u00f9 les temps de stockage sont tr\u00e8s brefs, voire inexistants, uniquement ce qui est n\u00e9cessaire afin de livrer un paquet ou une marchandise pratiquement sans traitement interm\u00e9diaire Ils permettent de r<strong>\u00e9duire les co\u00fbts<\/strong> de stockage, de distribution, d&rsquo;inventaire et de personnel, mais impliquent un <strong>changement dans le mod\u00e8le traditionnel d&rsquo;entreposage<\/strong>, en exigeant des espaces proches des centres-villes et des grandes villes, bien connect\u00e9s et o\u00f9 la taille passe \u00e0 un second plan en faveur de la versatilit\u00e9 et de la flexibilit\u00e9s des \u00e9l\u00e9ments de stockage. <\/span><\/p>\n<p><span style=\"font-size: 11pt;\"><a href=\"https:\/\/estanteriasrecord.com\/fr\/produits\/rayonnage-leger-perfore-classique\">Des solutions de chargement manuel<\/a>&nbsp;qui permettent de travailler avec de multiples r\u00e9f\u00e9rences aux volumes et tailles divers, \u00e0 la rotation \u00e9lev\u00e9e, s&rsquo;imposent \u00e0 des solutions con\u00e7ues pour des palettes ou pour \u00eatre g\u00e9r\u00e9es par des \u00e9l\u00e9ments m\u00e9caniques n\u00e9cessitant une surface plus grande et dont la rentabilit\u00e9 est impossible hors des zones industrielles.<\/span><\/p>\n<p><span style=\"font-size: 11pt;\">Le changement dans les processus, la technologie et l&rsquo;actualisation des rayonnages et des \u00e9l\u00e9ments de stockage \u00e0 cette nouvelle r\u00e9alit\u00e9 est, de fait, vitale pour les entreprises logistiques ; et dans la plupart des cas leur survie en d\u00e9pend, la technologie \u00e9tant l&rsquo;\u00e9l\u00e9ment-cl\u00e9.<\/span><\/p>\n<p><span style=\"font-size: 11pt;\">Selon notre exp\u00e9rience, les principales tendances de la transformation num\u00e9rique du secteur logistique \u00e0 prendre en compte sont les suivantes :<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-size: 11pt;\"><strong>La combinaison de technologies num\u00e9rise la cha\u00eene de valeur logistique.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 11pt;\">On ne peut plus parler des technologies s\u00e9par\u00e9ment, car beaucoup d&rsquo;entre elles agissent conjointement, multipliant leur effet. Le cloud (efficience et communication), le portable (applications) et le big data (connaissances du client) sont les ingr\u00e9dients d&rsquo;un cocktail tr\u00e8s disruptif. <\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-size: 11pt;\"><strong>L&rsquo;objectif devient \u00ab l&rsquo;exp\u00e9rience du client \u00bb.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 11pt;\">En suivant une r\u00e8gle quasi universelle dans le monde de l&rsquo;entreprise, le client est d\u00e9j\u00e0 l&rsquo;axe des produits et services logistiques. De fait, sa satisfaction et fid\u00e9lisation sont des \u00e9l\u00e9ments-cl\u00e9s pour les soci\u00e9t\u00e9s. <\/span><\/p>\n<p><span style=\"font-size: 11pt;\">La num\u00e9risation permet de mieux conna\u00eetre ses mod\u00e8les d&rsquo;utilisation, flux et demandes, en lui offrant un service excellent d\u00e8s le d\u00e9but de sa relation avec l&rsquo;entreprise, et de personnaliser les exp\u00e9riences.<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-size: 11pt;\"><strong>Les infrastructures deviennent \u00e9galement intelligentes.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 11pt;\">Bien qu&rsquo;\u00e0 un moindre rythme que dans d&rsquo;autres secteurs, les infrastructures de stockage se mettent \u00e0 jour et se num\u00e9risent. En ce sens, les technologies de \u00ab l&rsquo;Internet des choses \u00bb, qui combinent des capteurs, communications mobiles, algorithmes et big data jouent un r\u00f4le fondamental. <\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-size: 11pt;\"><strong>Toute technologie a sa place dans le monde de la logistique et l&rsquo;am\u00e9liore.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"font-size: 11pt;\">En tant que secteur proche du monde de l&rsquo;industrie, il existe de nombreuses technologies et des applications communes et celles qui se d\u00e9veloppent pour un cas concret sont g\u00e9n\u00e9ralement extrapolables au reste : robots qui automatisent l&rsquo;entreposage et la distribution de marchandises, syst\u00e8mes blockchain qui r\u00e9solvent des transactions ou l&rsquo;intelligence artificielle qui guide les v\u00e9hicules autonomes sont des preuves que les derni\u00e8res technologies sont en train de p\u00e9n\u00e9trer profond\u00e9ment dans ce secteur.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La r\u00e9volution technologique que nous vivons a un impact de plus en plus fort dans le monde de la logistique et du stockage. De plus en plus d&rsquo;entreprises vendent un plus grand nombre de produits en ligne et ont besoin de services de livraison plus rapides et meilleurs, que le client appr\u00e9cie, et qui influent [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":13323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[59],"tags":[],"class_list":["post-17404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record\" \/>\n<meta property=\"og:description\" content=\"La r\u00e9volution technologique que nous vivons a un impact de plus en plus fort dans le monde de la logistique et du stockage. De plus en plus d&rsquo;entreprises vendent un plus grand nombre de produits en ligne et ont besoin de services de livraison plus rapides et meilleurs, que le client appr\u00e9cie, et qui influent [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/\" \/>\n<meta property=\"og:site_name\" content=\"Estanter\u00edas Record\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/estanteriasrecord\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-27T10:47:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-24T17:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"magical_pro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"magical_pro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/\"},\"author\":{\"name\":\"magical_pro\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#\\\/schema\\\/person\\\/c28b4665b86ed0cfcf845c887a67eb4c\"},\"headline\":\"La technologie est de plus en plus pr\u00e9sente dans la logistique.\",\"datePublished\":\"2018-02-27T10:47:16+00:00\",\"dateModified\":\"2025-02-24T17:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/\"},\"wordCount\":648,\"publisher\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tendencias_en_logistica_para_2018.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/\",\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/\",\"name\":\"La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tendencias_en_logistica_para_2018.jpg\",\"datePublished\":\"2018-02-27T10:47:16+00:00\",\"dateModified\":\"2025-02-24T17:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#primaryimage\",\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tendencias_en_logistica_para_2018.jpg\",\"contentUrl\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/tendencias_en_logistica_para_2018.jpg\",\"width\":1200,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/revolution-technologique-secteur-logistique-et-stockage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La technologie est de plus en plus pr\u00e9sente dans la logistique.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/\",\"name\":\"Estanter\u00edas Record\",\"description\":\"Sistemas eficientes de almacenamiento\",\"publisher\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#organization\",\"name\":\"Estanter\u00edas Record\",\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_cab_doc.png\",\"contentUrl\":\"https:\\\/\\\/estanteriasrecord.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo_cab_doc.png\",\"width\":250,\"height\":119,\"caption\":\"Estanter\u00edas Record\"},\"image\":{\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/estanteriasrecord\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/#\\\/schema\\\/person\\\/c28b4665b86ed0cfcf845c887a67eb4c\",\"name\":\"magical_pro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g\",\"caption\":\"magical_pro\"},\"url\":\"https:\\\/\\\/estanteriasrecord.com\\\/fr\\\/author\\\/magical_pro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/","og_locale":"fr_FR","og_type":"article","og_title":"La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record","og_description":"La r\u00e9volution technologique que nous vivons a un impact de plus en plus fort dans le monde de la logistique et du stockage. De plus en plus d&rsquo;entreprises vendent un plus grand nombre de produits en ligne et ont besoin de services de livraison plus rapides et meilleurs, que le client appr\u00e9cie, et qui influent [&hellip;]","og_url":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/","og_site_name":"Estanter\u00edas Record","article_publisher":"https:\/\/www.facebook.com\/estanteriasrecord\/","article_published_time":"2018-02-27T10:47:16+00:00","article_modified_time":"2025-02-24T17:03:21+00:00","og_image":[{"width":1200,"height":810,"url":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg","type":"image\/jpeg"}],"author":"magical_pro","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"magical_pro","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#article","isPartOf":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/"},"author":{"name":"magical_pro","@id":"https:\/\/estanteriasrecord.com\/fr\/#\/schema\/person\/c28b4665b86ed0cfcf845c887a67eb4c"},"headline":"La technologie est de plus en plus pr\u00e9sente dans la logistique.","datePublished":"2018-02-27T10:47:16+00:00","dateModified":"2025-02-24T17:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/"},"wordCount":648,"publisher":{"@id":"https:\/\/estanteriasrecord.com\/fr\/#organization"},"image":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#primaryimage"},"thumbnailUrl":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/","url":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/","name":"La technologie est de plus en plus pr\u00e9sente dans la logistique. | Estanter\u00edas Record","isPartOf":{"@id":"https:\/\/estanteriasrecord.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#primaryimage"},"image":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#primaryimage"},"thumbnailUrl":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg","datePublished":"2018-02-27T10:47:16+00:00","dateModified":"2025-02-24T17:03:21+00:00","breadcrumb":{"@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#primaryimage","url":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg","contentUrl":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/06\/tendencias_en_logistica_para_2018.jpg","width":1200,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/estanteriasrecord.com\/fr\/revolution-technologique-secteur-logistique-et-stockage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/estanteriasrecord.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La technologie est de plus en plus pr\u00e9sente dans la logistique."}]},{"@type":"WebSite","@id":"https:\/\/estanteriasrecord.com\/fr\/#website","url":"https:\/\/estanteriasrecord.com\/fr\/","name":"Estanter\u00edas Record","description":"Sistemas eficientes de almacenamiento","publisher":{"@id":"https:\/\/estanteriasrecord.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estanteriasrecord.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/estanteriasrecord.com\/fr\/#organization","name":"Estanter\u00edas Record","url":"https:\/\/estanteriasrecord.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/estanteriasrecord.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/03\/logo_cab_doc.png","contentUrl":"https:\/\/estanteriasrecord.com\/wp-content\/uploads\/2024\/03\/logo_cab_doc.png","width":250,"height":119,"caption":"Estanter\u00edas Record"},"image":{"@id":"https:\/\/estanteriasrecord.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/estanteriasrecord\/"]},{"@type":"Person","@id":"https:\/\/estanteriasrecord.com\/fr\/#\/schema\/person\/c28b4665b86ed0cfcf845c887a67eb4c","name":"magical_pro","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3f557e3081c5b56eb83c595e7c177c2d80c9d4a7da37300e7785e1bef6fa5fb?s=96&d=mm&r=g","caption":"magical_pro"},"url":"https:\/\/estanteriasrecord.com\/fr\/author\/magical_pro\/"}]}},"_links":{"self":[{"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/posts\/17404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/comments?post=17404"}],"version-history":[{"count":1,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/posts\/17404\/revisions"}],"predecessor-version":[{"id":17405,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/posts\/17404\/revisions\/17405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/media\/13323"}],"wp:attachment":[{"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/media?parent=17404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/categories?post=17404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/estanteriasrecord.com\/fr\/wp-json\/wp\/v2\/tags?post=17404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}